{"id":79,"date":"2020-12-10T17:22:45","date_gmt":"2020-12-10T20:22:45","guid":{"rendered":"https:\/\/colegioportobrasil.com.br\/blog\/?p=79"},"modified":"2020-12-10T17:22:45","modified_gmt":"2020-12-10T20:22:45","slug":"minhas-rimas-de-cordel","status":"publish","type":"post","link":"https:\/\/colegioportobrasil.com.br\/blog\/2020\/12\/10\/minhas-rimas-de-cordel\/","title":{"rendered":"Minhas rimas de Cordel"},"content":{"rendered":"\n<p>O dia do Cordelista\n\u00e9 comemorado em 19 de Novembro, em homenagem a de Leandro Gomes de Barros, um\ndos maiores cordelistas do Brasil, nascido em 19 de novembro de 1865.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp; A literatura de cordel \u00e9 um g\u00eanero\nliter\u00e1rio tipicamente brasileiro, marcado pelo ritmo e pela poesia, trazendo\nconsigo a tradi\u00e7\u00e3o das hist\u00f3rias contadas. De maneira singular, o cordel traduz\nos costumes da oralidade em seus versos e pode contribuir para o que os\npequenos leitores desenvolvam a linguagem, o ritmo e as rela\u00e7\u00f5es entre escrita\ne fala. Os cord\u00e9is tamb\u00e9m podem ser declamados, encenados ou lidos de maneira\nl\u00fadica e divertida.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp; Os cord\u00e9is contam hist\u00f3rias sobre os contos\nde fadas, folclores, f\u00e1bulas, lendas, al\u00e9m de hist\u00f3rias t\u00edpicas e regionais do\nsert\u00e3o brasileiro. Com origem nos trovadores medievais, a tradi\u00e7\u00e3o cordelista\ncheia de ritmo veio de Portugal. Hoje conhecemos o cordel em suas\ncaracter\u00edstica tipicamente brasileiras, origin\u00e1rias do sert\u00e3o nordestino.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp; Com muita poesia e encantamento t\u00edpicos das\nleituras de cordel, essas produ\u00e7\u00f5es s\u00e3o \u00f3timas para leitura com beb\u00eas e\ncrian\u00e7as, estimulando a linguagem, dic\u00e7\u00e3o e musicalidade, al\u00e9m da ludicidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O dia do Cordelista \u00e9 comemorado em 19 de Novembro, em homenagem a de Leandro Gomes de Barros, um dos<\/p>\n","protected":false},"author":1,"featured_media":80,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/79"}],"collection":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=79"}],"version-history":[{"count":1,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/79\/revisions"}],"predecessor-version":[{"id":81,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/79\/revisions\/81"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/80"}],"wp:attachment":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=79"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=79"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}