{"id":137,"date":"2022-10-03T09:28:46","date_gmt":"2022-10-03T12:28:46","guid":{"rendered":"https:\/\/colegioportobrasil.com.br\/blog\/?p=137"},"modified":"2022-10-03T09:28:46","modified_gmt":"2022-10-03T12:28:46","slug":"9-brincadeiras-com-tinta-para-a-educacao-infantil","status":"publish","type":"post","link":"https:\/\/colegioportobrasil.com.br\/blog\/2022\/10\/03\/9-brincadeiras-com-tinta-para-a-educacao-infantil\/","title":{"rendered":"9 BRINCADEIRAS COM TINTA PARA A EDUCA\u00c7\u00c3O INFANTIL"},"content":{"rendered":"\n<ul><li><strong>Livros\n     para pintar:<\/strong>&nbsp;uma\n     das maneiras mais tradicionais \u00e9 recorrer aos livros de pintar, que\n     permitem aos pequenos usar v\u00e1rios materiais para colorir seus personagens\n     favoritos ou novos protagonistas em seu imagin\u00e1rio, da tinta guache \u00e0s\n     canetinhas.<\/li><li><strong>Pintura\n     com as m\u00e3os e os p\u00e9s:<\/strong>&nbsp;em\n     vez de contar com pinc\u00e9is, que tal usar as m\u00e3ozinhas e os pezinhos para\n     pintar? Al\u00e9m de divertido, essa \u00e9 uma \u00f3tima maneira de guardar uma\n     recorda\u00e7\u00e3o de quando os filhos ainda eram t\u00e3o pequenos e comprovar como\n     eles crescem r\u00e1pido.<\/li><li><strong>Pintura\n     com sal:<\/strong>&nbsp;em\n     uma folha de papel ou caixa de papel\u00e3o, fa\u00e7am desenhos com sal. Depois,\n     com um conta-gotas, aplique corante aliment\u00edcio dilu\u00eddo em \u00e1gua e veja\n     como isso criar\u00e1 belos efeitos, texturas e padr\u00f5es.<\/li><li><strong>Tinta de\n     gelo:<\/strong>&nbsp;ainda\n     com corante aliment\u00edcio e \u00e1gua, fa\u00e7a alguns cubos de gelo coloridos.\n     Quando estiverem congelados, leve para o quintal ou para a cal\u00e7ada e\n     brinque de pintar com as pedrinhas de gelo, que ainda ajudam a aliviar o\n     calor dos dias de sol.<\/li><li><strong>Sabonete\n     colorido:<\/strong>&nbsp;o\n     mesmo corante aliment\u00edcio pode ser misturado com sabonete l\u00edquido para\n     beb\u00eas e um pouco de \u00e1gua. Assim, al\u00e9m de ter uma tinta que sai f\u00e1cil, voc\u00ea\n     ainda incentiva as crian\u00e7as a entenderem a import\u00e2ncia da higiene!<\/li><li><strong>Pincel de\n     bolas de algod\u00e3o:<\/strong>&nbsp;ao\n     inv\u00e9s dos pinc\u00e9is tradicionais, voc\u00ea pode usar prendedores de roupa com\n     bolas de algod\u00e3o. Ent\u00e3o, \u00e9 s\u00f3 molhar na tinta e sair carimbando uma\n     cartolina ou outra superf\u00edcie grande.<\/li><li><strong>Tinta de\n     amido de milho:<\/strong>&nbsp;para\n     uma tinta cremosa e feita em casa, separe uma x\u00edcara de amido de milho,\n     meia x\u00edcara de \u00e1gua fervendo, uma x\u00edcara de \u00e1gua fria e corante\n     aliment\u00edcio. Misture o amido com a \u00e1gua fria at\u00e9 dissolver e, ent\u00e3o,\n     coloque \u00e1gua quente at\u00e9 atingir a consist\u00eancia desejada. Por fim, aplique\n     o corante aliment\u00edcio e use essa tinta cremosa para brincar!<\/li><li><strong>Pincel de\n     bolinhas:<\/strong>&nbsp;pegue\n     algumas bolinhas de gude ou de borracha e molhe-as na tinta. Ent\u00e3o,\n     coloque uma folha de sulfite ou papel cart\u00e3o dentro de uma bandeja e role\n     as bolinhas pela folha. Continue fazendo isso at\u00e9 terminar o quadro de\n     arte abstrata!<\/li><li><strong>Pintura\n     \u201cespirrada\u201d:<\/strong>&nbsp;a\n     ideia consiste em pegar algum objeto, coloc\u00e1-lo na tinta misturada com\n     \u00e1gua e, ent\u00e3o, jogar em uma cartolina ou papel\u00e3o bem grande. Conforme o\n     objeto bater na superf\u00edcie, ele ir\u00e1 fazer uma mancha super divertida e\n     colorida. Por\u00e9m, tome cuidado com as roupas, paredes e tudo o que estiver\n     ao redor: \u00e9 melhor fazer isso no meio do quintal e com tinta lav\u00e1vel.<\/li><\/ul>\n\n\n\n<p>Muitas\ndessas&nbsp;brincadeiras com tinta para fazem sujeira, \u00e9 verdade, mas aquela\nsujeira saud\u00e1vel e gostosa. Por isso, o ideal \u00e9 usar roupas mais velhas e ficar\nem algum lugar externo, combinado?&nbsp;<br>\n<br>\n<strong>Fonte texto:<\/strong> https:\/\/quindim.com.br\/blog\/a-importancia-da-pintura-na-educacao-infantil\/<br>\n<strong>Fonte imagem:<\/strong> &lt;a\nhref=&#8217;https:\/\/br.freepik.com\/fotos-vetores-gratis\/mae-e-bebe&#8217;&gt;M\u00e3e e beb\u00ea\nfoto criado por freepic.diller &#8211; br.freepik.com&lt;\/a&gt;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Livros para pintar:&nbsp;uma das maneiras mais tradicionais \u00e9 recorrer aos livros de pintar, que permitem aos pequenos usar v\u00e1rios materiais<\/p>\n","protected":false},"author":1,"featured_media":139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/137"}],"collection":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":1,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/137\/revisions"}],"predecessor-version":[{"id":140,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/137\/revisions\/140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/139"}],"wp:attachment":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}