{"id":126,"date":"2022-09-08T09:22:30","date_gmt":"2022-09-08T12:22:30","guid":{"rendered":"https:\/\/colegioportobrasil.com.br\/blog\/?p=126"},"modified":"2022-10-03T09:23:52","modified_gmt":"2022-10-03T12:23:52","slug":"brincadeiras-para-educacao-infantil","status":"publish","type":"post","link":"https:\/\/colegioportobrasil.com.br\/blog\/2022\/09\/08\/brincadeiras-para-educacao-infantil\/","title":{"rendered":"Brincadeiras para educa\u00e7\u00e3o infantil"},"content":{"rendered":"\n<p>As brincadeiras s\u00e3o ferramentas importantes para a aprendizagem\ndas crian\u00e7as, por meio delas, as crian\u00e7as passar por est\u00edmulos que fazem com\nque elas se desenvolvam de maneira divertida.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Separamos algumas brincadeiras que estimulam as crian\u00e7as a se\ndesenvolverem:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">1.&nbsp;&nbsp;&nbsp;&nbsp;\nPega-pega<\/h2>\n\n\n\n<p>A\nbrincadeira chamada de &#8220;pega-pega&#8221; \u00e9 uma das mais conhecidas entre as\ncrian\u00e7as. N\u00e3o precisa de nenhum material espec\u00edfico e n\u00e3o tem um n\u00famero certo\nde participantes.<\/p>\n\n\n\n<p>Essa\natividade \u00e9 \u00f3tima para desenvolver o senso de dire\u00e7\u00e3o das crian\u00e7as, assim como\na agilidade, racioc\u00ednio e rapidez.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">2.&nbsp;&nbsp;&nbsp;&nbsp;\nBobinho<\/h2>\n\n\n\n<p>Como funciona: Os participantes fazem um c\u00edrculo e tocam a bola\nuns para os outros. Uma crian\u00e7a \u00e9 escolhida para ficar no centro da roda e\ntentar pegar a posse de bola.<\/p>\n\n\n\n<p>Nesse exerc\u00edcio s\u00e3o trabalhados conceitos como coordena\u00e7\u00e3o e\nagilidade, al\u00e9m de outras habilidades motoras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3.Corre\ncotia<\/h2>\n\n\n\n<p>&#8220;Corre\ncotia&#8221; \u00e9 uma mistura de brincadeira de roda com &#8220;pega-pega&#8221;,\nonde tamb\u00e9m \u00e9 aperfei\u00e7oada a coordena\u00e7\u00e3o, equil\u00edbrio, rapidez e aten\u00e7\u00e3o. \u00c9\nainda uma atividade que exige a confian\u00e7a dos participantes.<\/p>\n\n\n\n<p>Gostaram\ndas dicas de atividades? <\/p>\n\n\n\n<p>Fonte: https:\/\/www.todamateria.com.br\/brincadeiras-para-educacao-infantil\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As brincadeiras s\u00e3o ferramentas importantes para a aprendizagem das crian\u00e7as, por meio delas, as crian\u00e7as passar por est\u00edmulos que fazem<\/p>\n","protected":false},"author":1,"featured_media":127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/126"}],"collection":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":1,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"predecessor-version":[{"id":128,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/126\/revisions\/128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/127"}],"wp:attachment":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}