{"id":101,"date":"2021-09-27T14:42:16","date_gmt":"2021-09-27T17:42:16","guid":{"rendered":"https:\/\/colegioportobrasil.com.br\/blog\/?p=101"},"modified":"2021-09-27T14:42:16","modified_gmt":"2021-09-27T17:42:16","slug":"4-beneficios-de-criar-uma-horta-na-escola","status":"publish","type":"post","link":"https:\/\/colegioportobrasil.com.br\/blog\/2021\/09\/27\/4-beneficios-de-criar-uma-horta-na-escola\/","title":{"rendered":"4 BENEF\u00cdCIOS DE CRIAR UMA HORTA NA ESCOLA"},"content":{"rendered":"\n<p>Para muitos, criar uma horta na escola,\nparece ser uma atividade sem conex\u00e3o com o papel acad\u00eamico da institui\u00e7\u00e3o de\nensino. Por\u00e9m, vale lembrar que, a escola \u00e9 um pilar importante para o\ndesenvolvimento do senso social, e aprender como a natureza se comporta e como\na preservar, faz parte disso.<br>\n<br>\n1 \u2013 SA\u00daDE F\u00cdSICA E MENTAL<br>\nEstimular o contato com a natureza desde cedo traz benef\u00edcios muito amplos para\na sa\u00fade f\u00edsica e mental, como, equil\u00edbrio da ansiedade, estimula a paci\u00eancia,\nsenso de cuidado e responsabilidade. E da parte f\u00edsica, fora os est\u00edmulos\nmentais que fazem muito bem para o corpo, o trabalho com a coordena\u00e7\u00e3o motora\nnessa fase de desenvolvimento \u00e9 algo indispens\u00e1vel.<br>\n<br>\n2 \u2013 DE ONDE OS ALIMENTOS SAUD\u00c1VEIS VEM?<br>\nAo mesmo tempo que a crian\u00e7a se diverte e est\u00edmulos positivos s\u00e3o feitos no\nc\u00e9rebro, eles tamb\u00e9m aprendem de onde legumes, verduras e frutos vem. Na\npr\u00e1tica aprendem como o ciclo da natureza se comporta, e como contribuir para\nisso.<br>\n<br>\n3\u2013 ALIMENTA\u00c7\u00c3O SAUD\u00c1VEL.<br>\nO cuidado com a horta aproxima as crian\u00e7as da pr\u00e1tica da alimenta\u00e7\u00e3o saud\u00e1vel.\nO fato de poder provar o que se levou algum tempo cuidando, esperando crescer,\ncausa curiosidade e expectativa sobre os alimentos. As crian\u00e7as se tornam muito\nmais receptivas aos legumes e verduras.<br>\n<br>\n4- CUIDAR DA NATUREZA<br>\nComo j\u00e1 citamos antes, este contato direto com o cuidado com a terra ajuda a\nconstruir o entendimento da import\u00e2ncia de cuidar da natureza. Uma vez que as\ncrian\u00e7as entendem que a natureza \u00e9 viva e precisa de cuidados, como todo ser,\nelas se desenvolvem durante a vida de forma mais consciente. \u00c9 ineg\u00e1vel que\nessa \u00e9 uma li\u00e7\u00e3o que toda a popula\u00e7\u00e3o do planeta deveria aprender e praticar\nimediatamente, pois, sabemos que o desmatamento j\u00e1 atingiu n\u00edveis\nirrevers\u00edveis. Educando nossas crian\u00e7as agora, nos traz esperan\u00e7as para o\nfuturo.<br>\n<br>\nFonte: https:\/\/escoladainteligencia.com.br\/blog\/razoes-para-criar-uma-horta-na-escola\/<br>\nFonte: &lt;a\nhref=&#8217;https:\/\/www.freepik.com\/photos\/nature&#8217;&gt;Nature photo created by freepik\n&#8211; www.freepik.com&lt;\/a&gt;<br>\n<br>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para muitos, criar uma horta na escola, parece ser uma atividade sem conex\u00e3o com o papel acad\u00eamico da institui\u00e7\u00e3o de<\/p>\n","protected":false},"author":1,"featured_media":102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/101"}],"collection":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=101"}],"version-history":[{"count":1,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/101\/revisions"}],"predecessor-version":[{"id":103,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/101\/revisions\/103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/102"}],"wp:attachment":[{"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegioportobrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}